{"id":1480,"count":46,"description":"","link":"https:\/\/escales.ponant.com\/us\/theme\/essential-us\/","name":"Essential","slug":"essential-us","taxonomy":"thematique","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Essential - Magazine de voyage Escales : interviews, inspirations et conseils | Magazine PONANT<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Essential - Magazine de voyage Escales : interviews, inspirations et conseils | Magazine PONANT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/escales.ponant.com\/us\/theme\/essential-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Magazine de voyage Escales : interviews, inspirations et conseils | Magazine PONANT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Cie_ponant\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Essential - Magazine de voyage Escales : interviews, inspirations et conseils | Magazine PONANT","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Archives des Essential - Magazine de voyage Escales : interviews, inspirations et conseils | Magazine PONANT","og_url":"https:\/\/escales.ponant.com\/us\/theme\/essential-us\/","og_site_name":"Magazine de voyage Escales : interviews, inspirations et conseils | Magazine PONANT","twitter_card":"summary_large_image","twitter_site":"@Cie_ponant","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/escales.ponant.com\/us\/theme\/essential-us\/","url":"https:\/\/escales.ponant.com\/us\/theme\/essential-us\/","name":"Archives des Essential - Magazine de voyage Escales : interviews, inspirations et conseils | Magazine PONANT","isPartOf":{"@id":"https:\/\/escales.ponant.com\/us\/#website"},"breadcrumb":{"@id":"https:\/\/escales.ponant.com\/us\/theme\/essential-us\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/escales.ponant.com\/us\/theme\/essential-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/escales.ponant.com\/us\/"},{"@type":"ListItem","position":2,"name":"Essential"}]},{"@type":"WebSite","@id":"https:\/\/escales.ponant.com\/us\/#website","url":"https:\/\/escales.ponant.com\/us\/","name":"Magazine de voyage Escales : interviews, inspirations et conseils | Magazine PONANT","description":"Le magazine de voyage par PONANT","publisher":{"@id":"https:\/\/escales.ponant.com\/us\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/escales.ponant.com\/us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/escales.ponant.com\/us\/#organization","name":"Ponant","url":"https:\/\/escales.ponant.com\/us\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/escales.ponant.com\/us\/#\/schema\/logo\/image\/","url":"https:\/\/escales.ponant.com\/wp-content\/uploads\/2020\/12\/logo-escales@2x.png","contentUrl":"https:\/\/escales.ponant.com\/wp-content\/uploads\/2020\/12\/logo-escales@2x.png","width":510,"height":174,"caption":"Ponant"},"image":{"@id":"https:\/\/escales.ponant.com\/us\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ponant","https:\/\/x.com\/Cie_ponant","https:\/\/www.instagram.com\/croisieres_ponant\/","https:\/\/www.pinterest.com\/ponantcruises\/","https:\/\/www.youtube.com\/user\/PonantCroisieres"]}]}},"_links":{"self":[{"href":"https:\/\/escales.ponant.com\/us\/wp-json\/wp\/v2\/thematique\/1480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escales.ponant.com\/us\/wp-json\/wp\/v2\/thematique"}],"about":[{"href":"https:\/\/escales.ponant.com\/us\/wp-json\/wp\/v2\/taxonomies\/thematique"}],"wp:post_type":[{"href":"https:\/\/escales.ponant.com\/us\/wp-json\/wp\/v2\/posts?thematique=1480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}